{"id":2,"count":2,"description":"","link":"https:\/\/demo.poplightdesign.com\/themes\/voyager\/category\/australia\/","name":"Australia","slug":"australia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/voyager\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/voyager\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/voyager\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/voyager\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}