{"id":29,"count":2,"description":"","link":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/product-category\/accessories\/","name":"Accessories","slug":"accessories","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/product_cat\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/product?product_cat=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}