{"id":4,"count":1,"description":"","link":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/category\/books\/","name":"Books","slug":"books","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.poplightdesign.com\/themes\/meadow\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}